{"id":5102,"count":3,"description":"Jenes hat dann 30-mal inoffizieller mitarbeiter (der stasi) Kampf kontra welchen Zufall verteidigt sein. -","link":"https:\/\/jinkaitrade.com\/en\/category\/hit-n-spin-199\/","name":"Hit N Spin 199","slug":"hit-n-spin-199","taxonomy":"category","parent":0,"meta":[],"_links":{"self":[{"href":"https:\/\/jinkaitrade.com\/en\/wp-json\/wp\/v2\/categories\/5102"}],"collection":[{"href":"https:\/\/jinkaitrade.com\/en\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/jinkaitrade.com\/en\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/jinkaitrade.com\/en\/wp-json\/wp\/v2\/posts?categories=5102"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}